{"id":116,"date":"2021-07-28T21:36:42","date_gmt":"2021-07-28T21:36:42","guid":{"rendered":"https:\/\/gr3solution.com\/domicile\/"},"modified":"2021-10-01T17:00:23","modified_gmt":"2021-10-01T17:00:23","slug":"domicile","status":"publish","type":"page","link":"https:\/\/gr3solution.com\/fr\/","title":{"rendered":"Domicile"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/GR3-header-video.mp4&Prime; module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb|auto||auto|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb48px\u00a0\u00bb text_letter_spacing=\u00a0\u00bb1px\u00a0\u00bb text_line_height=\u00a0\u00bb1em\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/material-for-content-boxes-and-bars-1.jpg\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb10px||10px||true|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb38px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb36px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb]<\/p>\n<p>L&rsquo;usinage du graphite \u00e0 son meilleur<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#474747&Prime; max_width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb86%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||29px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb30px||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb]<\/p>\n<p>GR3 est une nouvelle solution r\u00e9volutionnaire pour l&rsquo;usinage par voie humide du graphite. Il permet \u00e9galement l&rsquo;usinage de plusieurs mat\u00e9riaux avec la m\u00eame configuration et le m\u00eame outillage. Le r\u00e9sultat est un processus tr\u00e8s efficace qui offre un environnement de travail plus sain, un co\u00fbt d&rsquo;outillage inf\u00e9rieur et est capable d&rsquo;atteindre des tol\u00e9rances de .005.<\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00a0\u00bbhttps:\/\/player.vimeo.com\/video\/580436308&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(0,0,0,0)\u00a0\u00bb max_width=\u00a0\u00bb85%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#c4c4c4&Prime; width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb-85px||||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e\u00a0\u00bb text_font_size=\u00a0\u00bb32px\u00a0\u00bb text_line_height=\u00a0\u00bb1.1em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width_tablet=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb20px||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb27px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f638036d-e33e-4b44-80a8-028781fc8e1b%22:%91%93,%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Trois partenaires visionnaires, une nouvelle solution r\u00e9volutionnaire<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/gr3solution-section-background.jpg\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb45px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb35px||35px|30px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb35px|15px|35px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb background_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb background_image_tablet=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/material-for-content-boxes-and-bars-1.jpg\u00a0\u00bb background_enable_image_tablet=\u00a0\u00bbon\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/GF-logo-white.png\u00a0\u00bb title_text=\u00a0\u00bbGF+ logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||15px||false|false\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb]<\/p>\n<p>La derni\u00e8re innovation de GF combine leurs machines haut de gamme avec un filtre centrifuge tr\u00e8s efficace. Le r\u00e9sultat est une configuration compl\u00e8te qui non seulement r\u00e9sout le probl\u00e8me de l&rsquo;accumulation de poussi\u00e8re, mais permet \u00e9galement d&rsquo;utiliser une seule machine pour l&rsquo;usinage du graphite, du cuivre et de l&rsquo;acier.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/GR3-machine-1.jpg\u00a0\u00bb title_text=\u00a0\u00bbGR3-machine\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/gr3solution-section-background-left.jpg\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb45px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb35px|30px|35px||true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0px|15px|35px|15px|false|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb background_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb background_image_tablet=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/material-for-content-boxes-and-bars-1.jpg\u00a0\u00bb background_enable_image_tablet=\u00a0\u00bbon\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/coolant-image.jpg\u00a0\u00bb title_text=\u00a0\u00bbcoolant-image\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/blaser-logo-white.png\u00a0\u00bb title_text=\u00a0\u00bbblaser logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||20px||false|false\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb]<\/p>\n<p>Blasogind GTC 7 est l&rsquo;huile de coupe id\u00e9ale pour cette application. L&rsquo;huile excelle \u00e0 garder la poussi\u00e8re en solution, offrant ainsi un environnement d&rsquo;atelier beaucoup plus propre et des conditions de travail plus saines pour les machinistes. Elle r\u00e9duit \u00e9galement l&rsquo;usure des outils et aide \u00e0 obtenir de meilleures finitions de surface.<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/coolant-image.jpg\u00a0\u00bb title_text=\u00a0\u00bbcoolant-image\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/gr3solution-section-background.jpg\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb45px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb35px||35px|30px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb35px|15px|35px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb background_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb background_image_tablet=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/material-for-content-boxes-and-bars-1.jpg\u00a0\u00bb background_enable_image_tablet=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/Fraisa-white.png\u00a0\u00bb title_text=\u00a0\u00bbFraisa logo\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb60%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb||15px||false|false\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb]<\/p>\n<p>Les outils de fraisage de haute qualit\u00e9 de Fraisa peuvent d\u00e9sormais \u00eatre utilis\u00e9s sans rev\u00eatements co\u00fbteux sp\u00e9cifiques au graphite. Les machinistes peuvent atteindre une productivit\u00e9 accrue, des tol\u00e9rances \u00e9tonnantes et des finitions de surface impeccables, le tout pour une fraction du prix de l\u2019outillage traditionnel en graphite.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/GR3-tooling.jpg\u00a0\u00bb title_text=\u00a0\u00bbGR3-tooling\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb45px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_video src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/09\/landing-page-graph-4.mp4&Prime; module_class=\u00a0\u00bblwp-video-autoplay\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; title_text=\u00a0\u00bblanding page graph (4)\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#c4c4c4&Prime; width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb-85px||||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width=\u00a0\u00bb80%\u00a0\u00bb width_tablet=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb20px|auto||auto|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f638036d-e33e-4b44-80a8-028781fc8e1b%22:%91%93,%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Un mouliste peut d\u00e9sormais effectuer l\u2019ensemble du processus, des \u00e9lectrodes aux moules finis, avec un seul r\u00e9glage, sans aucune intervention manuelle. Les r\u00e9sultats augmentent la dur\u00e9e de vie des outils, une diminution du taux de rebut, une optimisation du temps de traitement et une \u00e9conomie annuelle moyenne de 100 000 $ par machine.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb40px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e\u00a0\u00bb text_font_size=\u00a0\u00bb35px\u00a0\u00bb text_line_height=\u00a0\u00bb1.1em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width_tablet=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb27px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f638036d-e33e-4b44-80a8-028781fc8e1b%22:%91%93,%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Demandez plus d&rsquo;informations sur la solution GR3<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-86\"><form id=\"wpforms-form-86\" class=\"wpforms-validate wpforms-form\" data-formid=\"86\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/116\" data-token=\"07469ef600a65c1bbb5161557ca641a2\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-86-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_1\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-86-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"Pr\u00e9nom *\" required><label for=\"wpforms-86-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-86-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Nom de famille \" required><label for=\"wpforms-86-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Nom<\/label><\/div><\/div><\/div><div id=\"wpforms-86-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_2\">Entreprise<\/label><input type=\"text\" id=\"wpforms-86-field_2\" class=\"wpforms-field-large\" name=\"wpforms[fields][2]\" placeholder=\"Entreprise \" ><\/div><div id=\"wpforms-86-field_7-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_7\">Ville<\/label><input type=\"text\" id=\"wpforms-86-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" placeholder=\"Ville\" ><\/div><div id=\"wpforms-86-field_16-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first\" data-field-id=\"16\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_16\">\u00c9tat<\/label><input type=\"text\" id=\"wpforms-86-field_16\" class=\"wpforms-field-large\" name=\"wpforms[fields][16]\" placeholder=\"\u00c9tat\" ><\/div><div id=\"wpforms-86-field_8-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third\" data-field-id=\"8\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_8\">Code postal<\/label><input type=\"text\" id=\"wpforms-86-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" placeholder=\"Code postal \" ><\/div><div id=\"wpforms-86-field_9-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third\" data-field-id=\"9\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_9\">Pays<\/label><input type=\"text\" id=\"wpforms-86-field_9\" class=\"wpforms-field-large\" name=\"wpforms[fields][9]\" placeholder=\"Pays \" ><\/div><div id=\"wpforms-86-field_13-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"13\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_13\">T\u00e9l\u00e9phone<\/label><input type=\"text\" id=\"wpforms-86-field_13\" class=\"wpforms-field-large\" name=\"wpforms[fields][13]\" placeholder=\"T\u00e9l\u00e9phone \" ><\/div><div id=\"wpforms-86-field_11-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half\" data-field-id=\"11\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-86-field_11\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-86-field_11\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][11]\" placeholder=\"Email *\" spellcheck=\"false\" required><\/div><div id=\"wpforms-86-field_12-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-86-field_12\">Dites-nous ce dont vous avez besoin <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-86-field_12\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-86-field_12_1\" name=\"wpforms[fields][12]\" value=\"J&#039;ai besoin de toute la solution\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-86-field_12_1\">J'ai besoin de toute la solution<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-86-field_12_2\" name=\"wpforms[fields][12]\" value=\"j&#039;ai besoin de liquide de refroidissement\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-86-field_12_2\">j'ai besoin de liquide de refroidissement<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-86-field_12_3\" name=\"wpforms[fields][12]\" value=\"j&#039;ai besoin d&#039;outillage\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-86-field_12_3\">j'ai besoin d'outillage<\/label><\/li><\/ul><\/div><div id=\"wpforms-86-field_14-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-86-field_14\">Politique de donn\u00e9es <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-86-field_14\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-86-field_14_1\" name=\"wpforms[fields][14][]\" value=\"J&#039;accepte *\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-86-field_14_1\">J'accepte *<\/label><\/li><\/ul><div class=\"wpforms-field-description\">En soumettant ce formulaire, vous acceptez notre <a href=\"\/fr\/politique-de-protection-des-donnees-2\/\">Politique de protection des donn\u00e9es<\/a><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"86\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-86\" class=\"wpforms-submit\" data-alt-text=\"Envoi en cours...\" data-submit-text=\"Soumettre\" aria-live=\"assertive\" value=\"wpforms-submit\">Soumettre<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbgcid-1a2e1e2d-4b44-4ceb-a1fd-a0d22ad11517&Prime; custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%93,%22gcid-1a2e1e2d-4b44-4ceb-a1fd-a0d22ad11517%22:%91%22background_color%22%93}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbgcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e\u00a0\u00bb text_font_size=\u00a0\u00bb27px\u00a0\u00bb text_line_height=\u00a0\u00bb1.2em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb width_tablet=\u00a0\u00bb80%\u00a0\u00bb width_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb|auto||auto|false|true\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb24px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-f638036d-e33e-4b44-80a8-028781fc8e1b%22:%91%93,%22gcid-ddbdfffd-003f-4253-8d4b-460d26e57a0e%22:%91%22text_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Si vous souhaitez en savoir plus sur chacun des partenaires, cliquez ci-dessous pour visiter leur site web.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/GF-logo-1.png\u00a0\u00bb title_text=\u00a0\u00bbGF+ logo\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.gfms.com\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb47%\u00a0\u00bb width_tablet=\u00a0\u00bb35%\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb6px||||false|false\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/Fraisa-1.png\u00a0\u00bb title_text=\u00a0\u00bbFraisa\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.fraisa.com\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb50%\u00a0\u00bb width_tablet=\u00a0\u00bb40%\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/gr3solution.com\/wp-content\/uploads\/2021\/07\/blaser-logo-1.png\u00a0\u00bb title_text=\u00a0\u00bbblaser logo \u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.blaser.com\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bb\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.9.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb50%\u00a0\u00bb width_tablet=\u00a0\u00bb35%\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_margin=\u00a0\u00bb15px||||false|false\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;usinage du graphite \u00e0 son meilleurGR3 est une nouvelle solution r\u00e9volutionnaire pour l&rsquo;usinage par voie humide du graphite. Il permet \u00e9galement l&rsquo;usinage de plusieurs mat\u00e9riaux avec la m\u00eame configuration et le m\u00eame outillage. Le r\u00e9sultat est un processus tr\u00e8s efficace qui offre un environnement de travail plus sain, un co\u00fbt d&rsquo;outillage inf\u00e9rieur et est capable [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-116","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/pages\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":0,"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/pages\/116\/revisions"}],"wp:attachment":[{"href":"https:\/\/gr3solution.com\/fr\/wp-json\/wp\/v2\/media?parent=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}